{"id":1229,"date":"2008-09-12T16:41:48","date_gmt":"2008-09-12T14:41:48","guid":{"rendered":"https:\/\/www.clubclayregazzoni.it\/wps\/?p=1229"},"modified":"2023-05-02T16:42:15","modified_gmt":"2023-05-02T14:42:15","slug":"il-paese-in-campo-per-dare-un-futuro-al-piccolo-fabio","status":"publish","type":"post","link":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/2008\/09\/12\/il-paese-in-campo-per-dare-un-futuro-al-piccolo-fabio\/","title":{"rendered":"Il paese in campo per dare un futuro al piccolo Fabio"},"content":{"rendered":"<p>Testata: <strong>Il Cittadino<\/strong>.<\/p>\n<p>Anche un piccolo paese sulle rive del Po come Caselle Landi ha deciso di mobilitarsi per la causa di Fabio Muroni, il bambino di 3 anni residente a Cadilana, affetto da una malattia rarissima, la sindrome di West. Sono molti i comuni del Lodigiano che si sono impegnati a promuovere raccolte fondi per permettere alla famiglia del piccolo Fabio di sostenere la spesa per un ciclo di cure negli Stati Uniti, presso l?ospedale di Fort Lauderdale, in Florida, dove le strutture e le terapie particolari che potr\u00e0 seguire, garantiranno un futuro pi\u00f9 sereno al bambino. Caselle Landi non ha voluto essere da meno. \u00ab?La nostra piccola comunit\u00e0 &#8211; ci spiega Laura Covelli, che coordina l?iniziativa &#8211; ha pensato pertanto di promuovere una raccolta fondi in occasione di due eventi che si sono realizzati a Caselle Landi: il Gran Gal\u00e0 Lirico e il Canta Caselle. Durante queste due serate abbiamo allestito un piccolo banchetto per dare maggiori informazioni sulla storia del bambino e per raccogliere le offerte donate dai partecipanti alle due manifestazioni. I casellesi hanno risposto con la generosit\u00e0 che da sempre contraddistingue la gente bassaiola ai nostri appelli. Siamo cos\u00ec riusciti a raccogliere la cifra di 1.700 euro. Anche l?amministrazione comunale ha voluto partecipare all? importante iniziativa di solidariet\u00e0. Speriamo che i progetti di raccolta fondi a favore del piccolo Fabio continuino per ridare la speranza a questo bambino e per garantirgli un futuro migliore insieme con la sua la famiglia?\u00bb.Ricordiamo che chi volesse contribuire alla causa del piccolo Fabio pu\u00f2 farlo attraverso bonifico bancario su: c\/c Banca di Credito Cooperativo Laudense di Corte Palasio &#8211; Codice Iban Internazionale IT90 R087 9433 0400 0000 0515 295Codice Iban Nazionale Cin R Abi 08794 Cab 33040 C\/C 000000515295. Causale Donazione per Fabio Muroni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Cittadino<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"disable_featured_image":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1229","post","type-post","status-publish","format-standard","hentry","category-rassegna-stampa"],"_links":{"self":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":1,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1230"}],"wp:attachment":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/tags?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}