{"id":1247,"date":"2008-08-19T16:51:18","date_gmt":"2008-08-19T14:51:18","guid":{"rendered":"https:\/\/www.clubclayregazzoni.it\/wps\/?p=1247"},"modified":"2023-05-02T16:51:40","modified_gmt":"2023-05-02T14:51:40","slug":"a-spino-dadda-un-mercatino-per-aiutare-il-piccolo-fabio","status":"publish","type":"post","link":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/2008\/08\/19\/a-spino-dadda-un-mercatino-per-aiutare-il-piccolo-fabio\/","title":{"rendered":"A Spino d&#8217;Adda un mercatino per aiutare il piccolo Fabio"},"content":{"rendered":"<p>Testata: <strong>Il Cittadino<\/strong>.<\/p>\n<p>Spino. Quando si \u00e8 trattato di decidere a chi dedicare la festa dell&#8217;estate, tutti hanno pensato subito al piccolo Fabio Muroni. Il bimbo di Corte Palasio \u00e8 affetto da una grave malattia, per curarsi deve volare in Florida; cos\u00ec in questi mesi il territorio si \u00e8 mobilitato per realizzare la sua grande speranza.Adesso tocca al Centro ricreativo estivo per l&#8217;infanzia di Spino, dove tutti gli anni i bambini lavorano insieme durante spettacoli e laboratori creativi. Alla fine dell&#8217;avventura, si organizza uno spettacolo seguito da un mercatino, dove si mettono in vendita i &#8220;lavoretti&#8221; realizzati dai pi\u00f9 piccoli. L&#8217;appuntamento \u00e8 fissato per il 23 luglio alle 20.45, presso la cascina Carlotta di Spino. Il ricavato \u00e8 destinato ogni volta ad un&#8217;associazione diversa, ora arriver\u00e0 sul conto corrente che la parrocchia di Cadilana ha messo a disposizione per Fabio.Per chi fosse interessato ad una donazione, il conto della parrocchia presso la Banca di Credito Cooperativo di Corte Palasio ha le seguenti coordinate bancarie nazionali: Bban: Cin Bban: R; Abi: 08794; Cab: 33040; conto: 000000515295. Nella causale \u00e8 necessario specificare &#8220;offerta per Fabio Muroni&#8221;. (Gr. Bo.)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Cittadino<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"disable_featured_image":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1247","post","type-post","status-publish","format-standard","hentry","category-rassegna-stampa"],"_links":{"self":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":1,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions"}],"predecessor-version":[{"id":1248,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions\/1248"}],"wp:attachment":[{"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/media?parent=1247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/categories?post=1247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubclayregazzoni.it\/wps\/index.php\/wp-json\/wp\/v2\/tags?post=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}